{"id":570,"count":162,"description":"ULPMAT es un fabricante profesional de materiales de recubrimiento, dedicado a suministrar c\u00e1todos para sputtering y materiales de evaporaci\u00f3n de la m\u00e1s alta calidad.\r\n\r\nOfrecemos una gama completa de c\u00e1todos para sputtering que incluye metales, aleaciones, cer\u00e1micas y c\u00e1todos compuestos personalizados. Tanto si necesita c\u00e1todos planos como rotativos, tenemos la experiencia necesaria para satisfacer una amplia gama de aplicaciones.","link":"https:\/\/ulpmat.com\/es\/product-category\/materiales-para-la-deposicion-de-peliculas-delgadas\/catodos-para-sputtering-de-aleaciones\/","name":"C\u00e1todos para sputtering de aleaciones","slug":"catodos-para-sputtering-de-aleaciones","taxonomy":"product_cat","parent":1177,"meta":[],"menu_order":0,"acf":[],"_links":{"self":[{"href":"https:\/\/ulpmat.com\/es\/wp-json\/wp\/v2\/product_cat\/570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ulpmat.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/ulpmat.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/ulpmat.com\/es\/wp-json\/wp\/v2\/product_cat\/1177"}],"wp:post_type":[{"href":"https:\/\/ulpmat.com\/es\/wp-json\/wp\/v2\/product?product_cat=570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}